{"id":2939,"date":"2023-11-24T14:40:16","date_gmt":"2023-11-24T19:40:16","guid":{"rendered":"https:\/\/musicteam.com\/?p=2939"},"modified":"2025-12-09T13:28:17","modified_gmt":"2025-12-09T18:28:17","slug":"redevances-black-box","status":"publish","type":"post","link":"https:\/\/musicteam.com\/fr\/redevances-black-box\/","title":{"rendered":"La black box: ces redevances perdues qui vous appartiennent"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-text fusion-title-size-one\"><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;--fontSize:54;line-height:1.16;\"><\/h1><\/div><div class=\"fusion-image-element \" style=\"--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"300\" height=\"200\" alt=\"Unclaimed royalties end up in the black box. \" title=\"black-box-royalties\" src=\"https:\/\/musicteam.com\/wp-content\/uploads\/2023\/11\/black-box-royalties-300x200.jpg\" class=\"img-responsive wp-image-2931\" srcset=\"https:\/\/musicteam.com\/wp-content\/uploads\/2023\/11\/black-box-royalties-200x133.jpg 200w, https:\/\/musicteam.com\/wp-content\/uploads\/2023\/11\/black-box-royalties-400x267.jpg 400w, https:\/\/musicteam.com\/wp-content\/uploads\/2023\/11\/black-box-royalties-600x400.jpg 600w, https:\/\/musicteam.com\/wp-content\/uploads\/2023\/11\/black-box-royalties-800x533.jpg 800w, https:\/\/musicteam.com\/wp-content\/uploads\/2023\/11\/black-box-royalties.jpg 1100w\" sizes=\"(max-width: 1024px) 100vw, (max-width: 640px) 100vw, 300px\" \/><\/span><\/div><div class=\"fusion-text fusion-text-1\"><h1><strong>La black box: ces redevances perdues qui vous appartiennent<\/strong><\/h1>\n<p><span style=\"font-weight: 400;\">Avez-vous d\u00e9j\u00e0 entendu parler de la notion de <\/span><i><span style=\"font-weight: 400;\">black box<\/span><\/i><span style=\"font-weight: 400;\"> dans l&rsquo;industrie musicale? Il s&rsquo;agit d&rsquo;un concept \u00e9nigmatique qui plonge souvent les auteurs-compositeurs et les artistes dans l\u2019ignorance au sujet de leurs redevances. Nous parlons ici de sommes colossales, se chiffrant en centaines de millions de dollars.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dans cet article, <\/span><a href=\"https:\/\/musicteam.com\/fr\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">MusicTeam\u00ae<\/span><\/a><span style=\"font-weight: 400;\"> vous \u00e9claire sur la signification des redevances de la <\/span><i><span style=\"font-weight: 400;\">black box<\/span><\/i><span style=\"font-weight: 400;\">, les raisons pour lesquelles elles restent souvent non r\u00e9clam\u00e9es, l&rsquo;impact financier que peuvent avoir ces redevances non per\u00e7ues, ainsi que les moyens de pr\u00e9venir la disparition de vos pr\u00e9cieuses redevances d&rsquo;ex\u00e9cution publique et de reproduction m\u00e9canique.<\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-2\"><h2><strong>Qu&rsquo;est-ce que la <i>black box<\/i> dans l&rsquo;industrie musicale ?<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Dans l&rsquo;industrie musicale, le terme <\/span><i><span style=\"font-weight: 400;\">black box<\/span><\/i><span style=\"font-weight: 400;\">, ou \u00ab bo\u00eete noire \u00bb en fran\u00e7ais, d\u00e9signe un ensemble de redevances qui demeurent non attribu\u00e9es et non r\u00e9clam\u00e9es. Ces redevances proviennent de diverses sources, notamment des services de diffusion en continu, de la diffusion radiophonique et de l\u2019ex\u00e9cution publique d\u2019\u0153uvres musicales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La d\u00e9nomination <\/span><i><span style=\"font-weight: 400;\">black box <\/span><\/i><span style=\"font-weight: 400;\">ou \u00ab bo\u00eete noire \u00bb tire son origine de la nature myst\u00e9rieuse de ces fonds, qui s&rsquo;accumulent avec le temps et demeurent souvent inconnus des b\u00e9n\u00e9ficiaires l\u00e9gitimes. Rien qu&rsquo;en 2021, aux \u00c9tats-Unis, la MLC (<\/span><a href=\"https:\/\/www.themlc.com\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Mechanical Licensing Collective<\/span><\/a><span style=\"font-weight: 400;\">), l&rsquo;entit\u00e9 charg\u00e9e de collecter les redevances num\u00e9riques m\u00e9caniques sur les \u0153uvres musicales, a signal\u00e9 un montant de 424 millions de dollars (USD) de redevances non r\u00e9clam\u00e9es, enfouies dans cette \u00ab bo\u00eete noire \u00bb.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les redevances de la <\/span><i><span style=\"font-weight: 400;\">black box<\/span><\/i><span style=\"font-weight: 400;\"> englobent les redevances li\u00e9es tant aux \u0153uvres musicales qu&rsquo;aux enregistrements sonores. Dans cet article, nous nous penchons plus sp\u00e9cifiquement sur les redevances associ\u00e9es aux \u0153uvres musicales. Deux cat\u00e9gories principales se d\u00e9gagent : celles li\u00e9es aux ex\u00e9cutions publiques et celles relatives \u00e0 la reproduction m\u00e9canique. Concentrons-nous ici sur les redevances li\u00e9es aux ex\u00e9cutions publiques.<\/span><\/p>\n<h2><strong>D&rsquo;o\u00f9 proviennent les redevances li\u00e9es \u00e0 l&rsquo;ex\u00e9cution publique ?\u00a0<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">En ce qui concerne l&rsquo;ex\u00e9cution publique, nous pouvons penser \u00e0 des \u00e9v\u00e9nements publics tels que les concerts, par exemple, mais aussi \u00e0 l&rsquo;<\/span><a href=\"https:\/\/musicteam.com\/fr\/economie-de-la-diffusion-en-continu\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">\u00e9conomie de la diffusion<\/span><\/a><span style=\"font-weight: 400;\"> (<\/span><i><span style=\"font-weight: 400;\">streaming<\/span><\/i><span style=\"font-weight: 400;\">).<\/span><\/p>\n<h3>Commerces et performances en direct : concerts, festivals, etc.<\/h3>\n<p><span style=\"font-weight: 400;\">Dans divers \u00e9tablissements publics tels que restaurants, magasins, salles de concert, et festivals, il rev\u00eat une importance cruciale pour les entreprises d&rsquo;acqu\u00e9rir des licences aupr\u00e8s d&rsquo;organismes tels qu&rsquo;<\/span><a href=\"https:\/\/www.entandemlicensing.com\/fr\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Entandem<\/span><\/a><span style=\"font-weight: 400;\">. Ces licences autorisent les entreprises \u00e0 diffuser de la musique en public, g\u00e9n\u00e9rant ainsi des redevances sur les droits d&rsquo;ex\u00e9cution. Une fois la musique diffus\u00e9e, elle doit \u00eatre d\u00e9clar\u00e9e aupr\u00e8s de la SOCAN ou signal\u00e9e via sa D\u00e9claration d&rsquo;\u0153uvres musicales ex\u00e9cut\u00e9es en spectacle (DOMES), pour que les redevances puissent \u00eatre redistribu\u00e9es \u00e0 ses membres.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le montant de cette licence d\u00e9pend de la taille de l&rsquo;entreprise et du type d&rsquo;\u00e9v\u00e9nement. Soulignons \u00e9galement que les entreprises ne doivent pas utiliser les comptes personnels Spotify ou Apple Music de leurs employ\u00e9s \u00e0 des fins commerciales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pour une gestion efficace de la distribution des redevances li\u00e9es aux licences musicales, les \u00e9tablissements devraient envisager de tirer parti de <\/span><a href=\"https:\/\/www.tshoko.com\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">plateformes avanc\u00e9es qui simplifient la cr\u00e9ation et la transmission de rapports de diffusion<\/span><\/a><span style=\"font-weight: 400;\">. Ces plateformes garantissent que le contenu diffus\u00e9 en public est correctement identifi\u00e9 et rapidement communiqu\u00e9 \u00e0 la SOCAN, l&rsquo;organisation de perception des redevances. Ce processus assure une gestion minutieuse et une redistribution efficace des fonds vers\u00e9s \u00e0 Entandem pour l&rsquo;octroi de licences. Cela assure que ces fonds parviennent aux ayants droit.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De plus, dans le contexte des bo\u00eetes de nuit, de nombreuses entreprises de technologie de reconnaissance musicale (MRT) \u00e9mergent en collaboration avec des soci\u00e9t\u00e9s de gestion collective. Leur but : identifier les \u0153uvres musicales jou\u00e9es et r\u00e9mun\u00e9rer les titulaires de droits correspondants. Pour les repr\u00e9sentations musicales en direct, les concerts et les festivals, il est imp\u00e9ratif de d\u00e9clarer la liste des morceaux interpr\u00e9t\u00e9s, bien que cette \u00e9tape soit souvent n\u00e9glig\u00e9e.<\/span><\/p>\n<h3><strong>\u00c9conomie de la diffusion<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Les prestataires de services num\u00e9riques (DSP) tels qu&rsquo;Apple Music, Spotify, et autres, ont \u00e9tabli des accords avec les soci\u00e9t\u00e9s de gestion collective (PRO) \u00e0 l&rsquo;\u00e9chelle mondiale. Ces DSP fournissent des rapports et versent des redevances aux soci\u00e9t\u00e9s de gestion collective, qui ont la responsabilit\u00e9 de r\u00e9partir ces redevances sur les \u0153uvres musicales (\u00e0 la fois les droits d&rsquo;ex\u00e9cution et les droits m\u00e9caniques) provenant entre autres de la diffusion en continu. Toutefois, si les soci\u00e9t\u00e9s de gestion collective ne disposent pas de <a href=\"https:\/\/musicteam.com\/fr\/comment-ajouter-des-metadonnees-a-votre-musique\/\">m\u00e9tadonn\u00e9es pr\u00e9cises<\/a> pour une \u0153uvre musicale dans ces rapports, elles doivent utiliser des techniques de jumelages pour tenter d&rsquo;identifier l&rsquo;\u0153uvre ou ses ayants droit.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cette situation conduit \u00e0 ce que les redevances soient plac\u00e9es dans ce que l&rsquo;on appelle commun\u00e9ment la <\/span><i><span style=\"font-weight: 400;\">black box<\/span><\/i><span style=\"font-weight: 400;\">. Au lieu d&rsquo;\u00eatre directement attribu\u00e9es aux auteurs, compositeurs et paroliers, les organisations de droits d\u2019ex\u00e9cution (PRO) peuvent intervenir pour redistribuer les fonds de la <\/span><i><span style=\"font-weight: 400;\">black box<\/span><\/i><span style=\"font-weight: 400;\">, en les r\u00e9partissant de mani\u00e8re proportionnelle entre leurs membres ou en les r\u00e9investissant au sein de l&rsquo;organisation.<\/span><\/p>\n<h2><strong>Pourquoi les redevances de la <i>black box<\/i> ne sont-elles pas per\u00e7ues?<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Nous pouvons identifier trois raisons principales pour lesquelles les redevances de la <\/span><i><span style=\"font-weight: 400;\">black box<\/span><\/i><span style=\"font-weight: 400;\"> pour les \u0153uvres musicales ne sont pas encaiss\u00e9es :<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Les ayants droit ne sont pas membres d\u2019une soci\u00e9t\u00e9 de gestion gestion collective(PRO, CMO ou MRO) o\u00f9 les \u0153uvres musicales n\u2019y sont pas d\u00e9clar\u00e9es.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Les m\u00e9tadonn\u00e9es absentes ou incompl\u00e8tes. (Utilisez un <a href=\"https:\/\/musicteam.com\/fr\/gestion-de-catalogue-musical\/\">outil de gestion de catalogue musical<\/a> pour organiser vos ressources\u00a0!)<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Les rapports sont incomplets.<\/span><\/li>\n<\/ul>\n<h3><strong>1. Enregistrez-vous vos \u0153uvres musicales aupr\u00e8s d&rsquo;une PRO?<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">L&rsquo;<\/span><b>absence d&rsquo;affiliation \u00e0 une soci\u00e9t\u00e9 de gestion collective <\/b><span style=\"font-weight: 400;\">(PRO) et une <\/span><a href=\"https:\/\/musicteam.com\/fr\/declaration-oeuvres-enregistrements\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">d\u00e9claration de ses \u0153uvres musicales<\/span><\/a><span style=\"font-weight: 400;\"> d\u00e9faillante sont des facteurs qui contribuent \u00e0 maintenir les redevances emprisonn\u00e9es dans la <\/span><i><span style=\"font-weight: 400;\">black box<\/span><\/i><span style=\"font-weight: 400;\">. Lorsque les auteurs, compositeurs et paroliers ne s&rsquo;affilient pas \u00e0 une soci\u00e9t\u00e9 de gestion collective et ne proc\u00e8dent pas \u00e0 la d\u00e9claration ad\u00e9quat de leurs droits musicaux, ils passent \u00e0 c\u00f4t\u00e9 de m\u00e9canismes essentiels qui facilitent la collecte et la r\u00e9partition des redevances de droits d&rsquo;ex\u00e9cution pour leurs \u0153uvres musicales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ces soci\u00e9t\u00e9s de gestion collective jouent un r\u00f4le fondamental dans la surveillance et l&rsquo;octroi de licences pour la diffusion publique d&rsquo;\u0153uvres musicales. En l&rsquo;absence d&rsquo;affiliation, elles ne sont pas en mesure de suivre de mani\u00e8re efficace o\u00f9 et quand la musique est jou\u00e9e, ce qui entra\u00eene des pertes de redevances.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Bon \u00e0 savoir : le m\u00eame processus s&rsquo;applique aux redevances m\u00e9caniques ou de reproduction de votre \u0153uvre musicale. Certaines soci\u00e9t\u00e9s peuvent collecter ces redevances. Si cela n&rsquo;est pas le cas, vous devrez devenir membre d&rsquo;une soci\u00e9t\u00e9 qui collecte les droits de reproduction comme la SOCAN DR ou la CMRRA au Canada et enregistrer vos \u0153uvres musicales aupr\u00e8s d&rsquo;elle pour vous assurer de ne pas passer \u00e0 c\u00f4t\u00e9 de ces importantes redevances.<\/span><\/p>\n<h3><strong>2. L&rsquo;absence ou l&rsquo;inexactitude des m\u00e9tadonn\u00e9es<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">L&rsquo;<\/span><b>exactitude des m\u00e9tadonn\u00e9es <\/b><span style=\"font-weight: 400;\">constitue un autre d\u00e9fi majeur. Il arrive parfois que des redevances soient g\u00e9n\u00e9r\u00e9es, mais ne puissent pas \u00eatre attribu\u00e9es aux titulaires de droits en raison de l&rsquo;absence ou d&rsquo;erreur dans les m\u00e9tadonn\u00e9es. Cette situation survient lorsque les \u0153uvres musicales sont diffus\u00e9es avec des m\u00e9tadonn\u00e9es\u00a0 incompl\u00e8tes, rendant ainsi complexe l&rsquo;identification des ayants droit. Dans le contexte de la diffusion de musique en continu, il faut pr\u00eater une attention minutieuse \u00e0 l&rsquo;inclusion d&rsquo;\u00e9l\u00e9ments cl\u00e9s tels que l&rsquo;IPI (Interested Parties Information), les noms l\u00e9gaux des auteurs-compositeurs et l&rsquo;ISWC (International Standard Musical Work Code) lors du processus de distribution de la musique.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&rsquo;exactitude des m\u00e9tadonn\u00e9es repr\u00e9sente un d\u00e9fi particuli\u00e8rement ardu dans le cadre de la <\/span><a href=\"https:\/\/musicteam.com\/fr\/distribution-musicale\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">distribution musicale internationale<\/span><\/a><span style=\"font-weight: 400;\">. La musique transcende les fronti\u00e8res, et les artistes ont souvent un public mondial. Lors de la distribution \u00e0 l\u2019\u00e9tranger, d\u2019autres redevances peuvent \u00eatre g\u00e9n\u00e9r\u00e9es. Il est donc important de bien identifier sa musique pour ne pas les manquer.<\/span><\/p>\n<h3><strong>3. Vous n\u2019avez pas acc\u00e8s \u00e0 des rapports ad\u00e9quats<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Une autre raison pour laquelle les redevances de la <\/span><i><span style=\"font-weight: 400;\">black box, <\/span><\/i><span style=\"font-weight: 400;\">ou \u00ab bo\u00eete noire \u00bb, ne sont pas per\u00e7ues tient \u00e0 <\/span><b>l&rsquo;absence de syst\u00e8me moderne aux temps num\u00e9riques pour recevoir des rapports sur les ex\u00e9cutions publiques<\/b><span style=\"font-weight: 400;\">. M\u00eame lorsqu&rsquo;une \u0153uvre musicale est identifi\u00e9e lors d&rsquo;une ex\u00e9cution publique, son identification d\u00e9pend de l&rsquo;existence d&rsquo;un rapport correspondant. En l&rsquo;absence d&rsquo;un tel rapport, les redevances ne peuvent \u00eatre r\u00e9parties.<\/span><\/p>\n<h2><strong>Les redevances de la <i>black box<\/i> non r\u00e9clam\u00e9es font perdre de l&rsquo;argent aux artistes<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Les redevances non r\u00e9clam\u00e9es de la <\/span><i><span style=\"font-weight: 400;\">black box<\/span><\/i><span style=\"font-weight: 400;\"> ont un impact consid\u00e9rable sur les auteurs-compositeurs et les artistes, les privant de revenus durement acquis. Au lieu de b\u00e9n\u00e9ficier aux cr\u00e9ateurs, ces redevances s&rsquo;accumulent dans l&rsquo;obscurit\u00e9 de la <\/span><i><span style=\"font-weight: 400;\">black box<\/span><\/i><span style=\"font-weight: 400;\">, entra\u00eenant des pertes financi\u00e8res substantielles. Pour de nombreux auteurs-compositeurs, cette perte de revenus peut repr\u00e9senter une part cruciale de leurs moyens de subsistance. L&rsquo;absence de r\u00e9clamation de ces redevances peut engendrer des difficult\u00e9s financi\u00e8res qui entravent la capacit\u00e9 des cr\u00e9ateurs \u00e0 poursuivre leur carri\u00e8re, \u00e0 produire de la nouvelle musique ou \u00e0 investir dans leurs projets artistiques.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De plus, la question des droits d&rsquo;auteur non r\u00e9clam\u00e9s exacerbe les in\u00e9galit\u00e9s de revenus au sein de l&rsquo;industrie musicale. Les artistes \u00e9tablis et bien connect\u00e9s disposent souvent de m\u00e9canismes plus efficaces pour s&rsquo;assurer qu&rsquo;ils re\u00e7oivent leurs revenus, tandis que les cr\u00e9ateurs \u00e9mergents ou ind\u00e9pendants peuvent avoir du mal \u00e0 naviguer dans le paysage complexe des droits musicaux, des m\u00e9tadonn\u00e9es et des redevances. Cette disparit\u00e9 peut entraver la croissance et l&rsquo;expression cr\u00e9ative des artistes \u00e9mergents, perp\u00e9tuant ainsi des d\u00e9s\u00e9quilibres dans les r\u00e8gles du jeu.<\/span><\/p>\n<h2><strong>O\u00f9 va l&rsquo;argent?<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Les redevances non r\u00e9clam\u00e9es ont tendance \u00e0 demeurer dans la <\/span><i><span style=\"font-weight: 400;\">black box<\/span><\/i><span style=\"font-weight: 400;\"> pendant un certain laps de temps, et leur destin\u00e9e peut s&rsquo;av\u00e9rer assez complexe. La question fondamentale qui se pose est : o\u00f9 va cet argent non r\u00e9clam\u00e9?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tout d&rsquo;abord, certaines soci\u00e9t\u00e9s de gestion collective affectent une partie des redevances non r\u00e9clam\u00e9es \u00e0 un fonds commun en vue d&rsquo;une distribution \u00e9ventuelle parmi leurs membres affili\u00e9s. Bien que cela puisse garantir un certain degr\u00e9 d&rsquo;\u00e9quit\u00e9, cela peut aussi entra\u00eener une dilution des revenus pour les cr\u00e9ateurs actifs.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Deuxi\u00e8mement, les co\u00fbts administratifs jouent un r\u00f4le dans ce processus. Une portion des fonds non r\u00e9clam\u00e9s peut \u00eatre utilis\u00e9e pour couvrir les frais administratifs li\u00e9s \u00e0 la gestion et \u00e0 la distribution des redevances. Par cons\u00e9quent, une partie de l&rsquo;argent non r\u00e9clam\u00e9 contribue au financement des op\u00e9rations des soci\u00e9t\u00e9s.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dans certains cas, les redevances non r\u00e9clam\u00e9es peuvent \u00eatre cat\u00e9goris\u00e9es comme \u00ab\u00a0abandonn\u00e9es\u00a0\u00bb apr\u00e8s une p\u00e9riode d\u00e9termin\u00e9e. Ces redevances ne peuvent \u00eatre attribu\u00e9es \u00e0 personne et sont de facto perdues pour les ayants droits.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Enfin, certains accords contractuels, notamment ceux impliquant les maisons de disques et les \u00e9diteurs, peuvent leur donner droit \u00e0 la r\u00e9cup\u00e9ration des redevances non r\u00e9clam\u00e9es. Cela signifie qu&rsquo;une proportion encore plus r\u00e9duite de l&rsquo;argent parvient aux ayants droits eux-m\u00eames.<\/span><\/p>\n<h2><strong>Comment \u00e9viter que vos redevances sur les \u0153uvres musicales ne finissent dans la <i>black box<\/i>?<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Pour \u00e9viter que vos redevances durement gagn\u00e9es ne disparaissent dans la <\/span><i><span style=\"font-weight: 400;\">black box<\/span><\/i><span style=\"font-weight: 400;\">, il faut prendre des mesures proactives et bien comprendre le syst\u00e8me complexe de redevances de l&rsquo;industrie musicale. Voici quelques mesures que vous pouvez prendre pour prot\u00e9ger vos revenus :<\/span><\/p>\n<h3><strong>1. Enregistrez votre \u0153uvre musicale aupr\u00e8s d&rsquo;une soci\u00e9t\u00e9 de gestion collective (PRO, CMO, MLC ou MRO)<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Les soci\u00e9t\u00e9s de gestion collective, telles que la SOCAN, l&rsquo;ASCAP, le BMI, le PRS, la SACEM et la GEMA, pour n&rsquo;en nommer que quelques-unes, jouent un r\u00f4le fondamental dans la collecte et la distribution des redevances. En devenant membre d&rsquo;une <\/span><a href=\"https:\/\/musicteam.com\/fr\/societes-de-gestion-collective-et-associations-musicales-quebec-canada\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">soci\u00e9t\u00e9 de gestion collective<\/span><\/a><span style=\"font-weight: 400;\">, vous pouvez vous assurer que vos \u0153uvres musicales sont correctement enregistr\u00e9es et que les redevances sont per\u00e7ues de mani\u00e8re syst\u00e9matique \u00e0 chaque ex\u00e9cution, diffusion ou diffusion en continu de vos \u0153uvres. Ces organismes b\u00e9n\u00e9ficient d&rsquo;un vaste r\u00e9seau de partenaires internationaux, ce qui vous permet de percevoir des revenus non seulement dans votre pays d&rsquo;origine, mais \u00e9galement \u00e0 l&rsquo;\u00e9chelle mondiale.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Au Canada, il est \u00e9galement n\u00e9cessaire de devenir membre d&rsquo;une soci\u00e9t\u00e9 de gestion des droits m\u00e9caniques (MRO) tel que la SOCAN RR ou la CMRRA pour r\u00e9cup\u00e9rer vos redevances li\u00e9es \u00e0 la reproduction m\u00e9canique. <\/span><span style=\"font-weight: 400;\"><br \/>\n<\/span><span style=\"font-weight: 400;\">(Note : Dans certains pays, les PRO et les MRO sont la m\u00eame soci\u00e9t\u00e9.)<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il est imp\u00e9ratif de d\u00e9clarer vos \u0153uvres musicales \u00e0 ces soci\u00e9t\u00e9s. Bonne nouvelle : chez MusicTeam\u00ae, nous sommes \u00e0 m\u00eame de vous aider \u00e0 enregistrer vos \u0153uvres musicales.<\/span><\/p>\n<\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" target=\"_self\" href=\"https:\/\/app.musicteam.com\/signup\/\"><span class=\"fusion-button-text\">Je d\u00e9clare mes \u0153uvres musicales<\/span><\/a><\/div><div class=\"fusion-text fusion-text-3\"><h3><span style=\"font-weight: 400;\">2. Garantir des m\u00e9tadonn\u00e9es pr\u00e9cises et compl\u00e8tes<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Des <\/span><a href=\"https:\/\/musicteam.com\/fr\/metadonnees-droits-musicaux\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">m\u00e9tadonn\u00e9es musicales<\/span><\/a><span style=\"font-weight: 400;\"> exactes sont l&rsquo;\u00e9l\u00e9ment vital de la perception des droits d&rsquo;auteur. Les m\u00e9tadonn\u00e9es englobent des informations sur les auteurs, compositeurs, \u00e9diteurs et autres titulaires de droits, notamment leur IPI, ISNI ou IPN, ainsi que l&rsquo;ISWC pour les \u0153uvres musicales et l&rsquo;ISRC pour les enregistrements sonores. Lorsque vous distribuez de la musique aux DSP, vous devez fournir des donn\u00e9es compl\u00e8tes et pr\u00e9cises. Cela aide les PRO et les MRO \u00e0 identifier rapidement les titulaires de droits et \u00e0 garantir que les redevances sont dirig\u00e9es vers les ayants droit.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L&rsquo;absence ou l&rsquo;inexactitude des m\u00e9tadonn\u00e9es peut entra\u00eener le blocage des redevances dans la <\/span><i><span style=\"font-weight: 400;\">black box<\/span><\/i><span style=\"font-weight: 400;\">, rendant l&rsquo;identification des ayants droit particuli\u00e8rement difficile. Toutes les m\u00e9tadonn\u00e9es relatives \u00e0 vos \u0153uvres musicales et \u00e0 vos enregistrements sonores peuvent \u00eatre document\u00e9es dans votre profil MusicTeam\u00ae. Cette d\u00e9marche vous permettra de toujours disposer de m\u00e9tadonn\u00e9es pr\u00e9cises, pr\u00eates \u00e0 \u00eatre utilis\u00e9es pour la d\u00e9claration des droits musicaux ou pour la distribution, contribuant ainsi \u00e0 \u00e9viter des pertes de redevances inutiles.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">3. Conservez des enregistrements minutieux de l&rsquo;ex\u00e9cution de votre musique<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Il est peu r\u00e9aliste de demander aux cr\u00e9ateurs de constamment documenter leurs <\/span><i><span style=\"font-weight: 400;\">setlists<\/span><\/i><span style=\"font-weight: 400;\">. Cependant, il existe des technologies avanc\u00e9es qui simplifient le processus de communication des r\u00e9pertoires de chansons \u2013 ou <\/span><i><span style=\"font-weight: 400;\">setlists<\/span><\/i><span style=\"font-weight: 400;\"> \u2013 aux soci\u00e9t\u00e9s de gestion collective. Des plateformes telles que le portail de la <\/span><span style=\"font-weight: 400;\">SOCAN<\/span><span style=\"font-weight: 400;\">, <\/span><a href=\"https:\/\/www.seeqnc.com\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Seeqnc<\/span><\/a><span style=\"font-weight: 400;\"> et <\/span><a href=\"https:\/\/www.muzooka.com\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Muzooka<\/span><\/a><span style=\"font-weight: 400;\"> offrent aux artistes la possibilit\u00e9 de documenter de mani\u00e8re confidentielle leurs performances musicales, ce qui contribue \u00e0 garantir une distribution \u00e9quitable des redevances.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De plus, lorsque les artistes constatent que leur musique est diffus\u00e9e sur les plateformes de diffusion en continu (DSP), cela devrait id\u00e9alement \u00eatre refl\u00e9t\u00e9 au niveau de leur PRO. Bien que le pourcentage de redevances puisse \u00eatre moins \u00e9lev\u00e9 que celui de la distribution, chaque diffusion g\u00e9n\u00e8re des redevances pour la composition musicale, couvrant \u00e0 la fois les droits d&rsquo;ex\u00e9cution publique et les droits de reproduction m\u00e9canique.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">MusicTeam\u00ae vous aide \u00e0 collecter toutes vos redevances<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Pour \u00e9viter ces pertes, une gestion proactive de vos m\u00e9tadonn\u00e9es musicales est essentielle pour vous permettre de collecter ce qui vous revient de droit. Les redevances ne doivent pas finir dans la <\/span><i><span style=\"font-weight: 400;\">black box<\/span><\/i><span style=\"font-weight: 400;\"> mais plut\u00f4t dans vos poches.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Notre plateforme tout-en-un pour les cr\u00e9ateurs \u00e9mergents et ind\u00e9pendants est l\u00e0 pour vous aider. Nous pouvons d\u00e9clarer vos \u0153uvres musicales aupr\u00e8s de la SOCAN afin que vous perceviez ce qui vous est r\u00e9ellement d\u00fb. Collaborons ensemble et <\/span><a href=\"https:\/\/app.musicteam.com\/signup\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">cr\u00e9ez votre profil MusicTeam\u00ae<\/span><\/a><span style=\"font-weight: 400;\"> pour assurer une gestion efficace de vos droits musicaux.<\/span><\/p>\n<\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-2 fusion-button-default-span fusion-button-default-type\" target=\"_self\" href=\"https:\/\/app.musicteam.com\/signup\/\"><span class=\"fusion-button-text\">Cr\u00e9er un profil<\/span><\/a><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":2931,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"La bo\u00eete noire est un v\u00e9ritable fl\u00e9au de l&#039;industrie musicale. O\u00f9 finissent ces millions de dollars qui devraient revenir aux artistes et quelle est la solution?\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Chloe Dagenais\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/musicteam.com\/fr\/redevances-black-box\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_CA\" \/>\n\t\t<meta property=\"og:site_name\" content=\"MusicTeam\u00ae \u2013 All-in-one platform for music makers\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La black box : ces redevances musicales perdues | MusicTeam\u00ae\" \/>\n\t\t<meta property=\"og:description\" content=\"La bo\u00eete noire est un v\u00e9ritable fl\u00e9au de l&#039;industrie musicale. O\u00f9 finissent ces millions de dollars qui devraient revenir aux artistes et quelle est la solution?\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/musicteam.com\/fr\/redevances-black-box\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/musicteam.com\/wp-content\/uploads\/2023\/11\/black-box-royalties.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/musicteam.com\/wp-content\/uploads\/2023\/11\/black-box-royalties.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t\t<meta property=\"og:image:height\" content=\"733\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-11-24T19:40:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-12-09T18:28:17+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/musicteamapp\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La black box : ces redevances musicales perdues | MusicTeam\u00ae\" \/>\n\t\t<meta name=\"twitter:description\" content=\"La bo\u00eete noire est un v\u00e9ritable fl\u00e9au de l&#039;industrie musicale. O\u00f9 finissent ces millions de dollars qui devraient revenir aux artistes et quelle est la solution?\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/musicteam.com\/wp-content\/uploads\/2023\/11\/black-box-royalties.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/redevances-black-box\\\/#blogposting\",\"name\":\"La black box : ces redevances musicales perdues | MusicTeam\\u00ae\",\"headline\":\"La black box: ces redevances perdues qui vous appartiennent\",\"author\":{\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/author\\\/chloe\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/musicteam.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/black-box-royalties.jpg\",\"width\":1100,\"height\":733,\"caption\":\"Unclaimed royalties end up in the black box.\"},\"datePublished\":\"2023-11-24T14:40:16-05:00\",\"dateModified\":\"2025-12-09T13:28:17-05:00\",\"inLanguage\":\"fr-CA\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/redevances-black-box\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/redevances-black-box\\\/#webpage\"},\"articleSection\":\"Droits musicaux, Facultatif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/redevances-black-box\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/categorie\\\/droits-musicaux\\\/#listItem\",\"name\":\"Droits musicaux\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/categorie\\\/droits-musicaux\\\/#listItem\",\"position\":2,\"name\":\"Droits musicaux\",\"item\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/categorie\\\/droits-musicaux\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/redevances-black-box\\\/#listItem\",\"name\":\"La black box: ces redevances perdues qui vous appartiennent\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/redevances-black-box\\\/#listItem\",\"position\":3,\"name\":\"La black box: ces redevances perdues qui vous appartiennent\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/categorie\\\/droits-musicaux\\\/#listItem\",\"name\":\"Droits musicaux\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/#organization\",\"name\":\"MusicTeam\\u00ae\",\"description\":\"All-in-one platform for music makers\",\"url\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/musicteam.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-favicon-1.png\",\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/redevances-black-box\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/redevances-black-box\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/instagram.com\\\/musicteamapp\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@musicteamapp\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/53398324\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/author\\\/chloe\\\/#author\",\"url\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/author\\\/chloe\\\/\",\"name\":\"Chloe Dagenais\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/musicteam.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/cropped-Sony_PS30_Portrait-Test_Chloe_0324-LowRes-Bright-96x96.jpg\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/chloedagenais\\\/\"],\"description\":\"Chloe is the Founder and President of MusicTeam\\u00ae, a self-serve platform revolutionizing music catalog management, registrations, project delivery and distribution for music makers. With a background in information systems, she specializes in building technology-driven solutions that help artists, musicians, engineers and rights holders manage their music more efficiently. Her work in digital music rights began during her master's thesis, where she developed the proof-of-concept for a streamlined music catalog management system, a project that laid the foundation for MusicTeam\\u00ae. Recognizing the industry's need for better metadata accuracy and artist-driven solutions, she officially founded MusicTeam\\u00ae in 2020 to empower music creators through self-serve tools. Beyond her role as Founder and President of MusicTeam\\u00ae, Chlo\\u00e9 actively contributes to industry discussions on metadata integrity, rights management, and the future of music technology.\",\"jobTitle\":\"Founder\",\"alumniOf\":[{\"@type\":\"EducationalOrganization\",\"name\":\"Berklee College of Music\",\"sameAs\":\"https:\\\/\\\/www.berklee.edu\"},{\"@type\":\"EducationalOrganization\",\"name\":\"Birkbeck, University of London\",\"sameAs\":\"https:\\\/\\\/www.bbk.ac.uk\"}],\"knowsLanguage\":[\"English\",\"French\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/redevances-black-box\\\/#webpage\",\"url\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/redevances-black-box\\\/\",\"name\":\"La black box : ces redevances musicales perdues | MusicTeam\\u00ae\",\"description\":\"La bo\\u00eete noire est un v\\u00e9ritable fl\\u00e9au de l'industrie musicale. O\\u00f9 finissent ces millions de dollars qui devraient revenir aux artistes et quelle est la solution?\",\"inLanguage\":\"fr-CA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/redevances-black-box\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/author\\\/chloe\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/author\\\/chloe\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/musicteam.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/black-box-royalties.jpg\",\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/redevances-black-box\\\/#mainImage\",\"width\":1100,\"height\":733,\"caption\":\"Unclaimed royalties end up in the black box.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/redevances-black-box\\\/#mainImage\"},\"datePublished\":\"2023-11-24T14:40:16-05:00\",\"dateModified\":\"2025-12-09T13:28:17-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/\",\"name\":\"MusicTeam\\u00ae\",\"description\":\"All-in-one platform for music makers\",\"inLanguage\":\"fr-CA\",\"publisher\":{\"@id\":\"https:\\\/\\\/musicteam.com\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>La black box : ces redevances musicales perdues | MusicTeam\u00ae<\/title>\n\n","aioseo_head_json":{"title":"La black box : ces redevances musicales perdues | MusicTeam\u00ae","description":"La bo\u00eete noire est un v\u00e9ritable fl\u00e9au de l'industrie musicale. O\u00f9 finissent ces millions de dollars qui devraient revenir aux artistes et quelle est la solution?","canonical_url":"https:\/\/musicteam.com\/fr\/redevances-black-box\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/musicteam.com\/fr\/redevances-black-box\/#blogposting","name":"La black box : ces redevances musicales perdues | MusicTeam\u00ae","headline":"La black box: ces redevances perdues qui vous appartiennent","author":{"@id":"https:\/\/musicteam.com\/fr\/author\/chloe\/#author"},"publisher":{"@id":"https:\/\/musicteam.com\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/musicteam.com\/wp-content\/uploads\/2023\/11\/black-box-royalties.jpg","width":1100,"height":733,"caption":"Unclaimed royalties end up in the black box."},"datePublished":"2023-11-24T14:40:16-05:00","dateModified":"2025-12-09T13:28:17-05:00","inLanguage":"fr-CA","mainEntityOfPage":{"@id":"https:\/\/musicteam.com\/fr\/redevances-black-box\/#webpage"},"isPartOf":{"@id":"https:\/\/musicteam.com\/fr\/redevances-black-box\/#webpage"},"articleSection":"Droits musicaux, Facultatif"},{"@type":"BreadcrumbList","@id":"https:\/\/musicteam.com\/fr\/redevances-black-box\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/musicteam.com\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/musicteam.com\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/musicteam.com\/fr\/categorie\/droits-musicaux\/#listItem","name":"Droits musicaux"}},{"@type":"ListItem","@id":"https:\/\/musicteam.com\/fr\/categorie\/droits-musicaux\/#listItem","position":2,"name":"Droits musicaux","item":"https:\/\/musicteam.com\/fr\/categorie\/droits-musicaux\/","nextItem":{"@type":"ListItem","@id":"https:\/\/musicteam.com\/fr\/redevances-black-box\/#listItem","name":"La black box: ces redevances perdues qui vous appartiennent"},"previousItem":{"@type":"ListItem","@id":"https:\/\/musicteam.com\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/musicteam.com\/fr\/redevances-black-box\/#listItem","position":3,"name":"La black box: ces redevances perdues qui vous appartiennent","previousItem":{"@type":"ListItem","@id":"https:\/\/musicteam.com\/fr\/categorie\/droits-musicaux\/#listItem","name":"Droits musicaux"}}]},{"@type":"Organization","@id":"https:\/\/musicteam.com\/fr\/#organization","name":"MusicTeam\u00ae","description":"All-in-one platform for music makers","url":"https:\/\/musicteam.com\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/musicteam.com\/wp-content\/uploads\/2020\/07\/cropped-favicon-1.png","@id":"https:\/\/musicteam.com\/fr\/redevances-black-box\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/musicteam.com\/fr\/redevances-black-box\/#organizationLogo"},"sameAs":["https:\/\/instagram.com\/musicteamapp\/","https:\/\/www.youtube.com\/@musicteamapp","https:\/\/www.linkedin.com\/company\/53398324\/"]},{"@type":"Person","@id":"https:\/\/musicteam.com\/fr\/author\/chloe\/#author","url":"https:\/\/musicteam.com\/fr\/author\/chloe\/","name":"Chloe Dagenais","image":{"@type":"ImageObject","url":"https:\/\/musicteam.com\/wp-content\/uploads\/2024\/12\/cropped-Sony_PS30_Portrait-Test_Chloe_0324-LowRes-Bright-96x96.jpg"},"sameAs":["https:\/\/www.linkedin.com\/in\/chloedagenais\/"],"description":"Chloe is the Founder and President of MusicTeam\u00ae, a self-serve platform revolutionizing music catalog management, registrations, project delivery and distribution for music makers. With a background in information systems, she specializes in building technology-driven solutions that help artists, musicians, engineers and rights holders manage their music more efficiently. Her work in digital music rights began during her master's thesis, where she developed the proof-of-concept for a streamlined music catalog management system, a project that laid the foundation for MusicTeam\u00ae. Recognizing the industry's need for better metadata accuracy and artist-driven solutions, she officially founded MusicTeam\u00ae in 2020 to empower music creators through self-serve tools. Beyond her role as Founder and President of MusicTeam\u00ae, Chlo\u00e9 actively contributes to industry discussions on metadata integrity, rights management, and the future of music technology.","jobTitle":"Founder","alumniOf":[{"@type":"EducationalOrganization","name":"Berklee College of Music","sameAs":"https:\/\/www.berklee.edu"},{"@type":"EducationalOrganization","name":"Birkbeck, University of London","sameAs":"https:\/\/www.bbk.ac.uk"}],"knowsLanguage":["English","French"]},{"@type":"WebPage","@id":"https:\/\/musicteam.com\/fr\/redevances-black-box\/#webpage","url":"https:\/\/musicteam.com\/fr\/redevances-black-box\/","name":"La black box : ces redevances musicales perdues | MusicTeam\u00ae","description":"La bo\u00eete noire est un v\u00e9ritable fl\u00e9au de l'industrie musicale. O\u00f9 finissent ces millions de dollars qui devraient revenir aux artistes et quelle est la solution?","inLanguage":"fr-CA","isPartOf":{"@id":"https:\/\/musicteam.com\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/musicteam.com\/fr\/redevances-black-box\/#breadcrumblist"},"author":{"@id":"https:\/\/musicteam.com\/fr\/author\/chloe\/#author"},"creator":{"@id":"https:\/\/musicteam.com\/fr\/author\/chloe\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/musicteam.com\/wp-content\/uploads\/2023\/11\/black-box-royalties.jpg","@id":"https:\/\/musicteam.com\/fr\/redevances-black-box\/#mainImage","width":1100,"height":733,"caption":"Unclaimed royalties end up in the black box."},"primaryImageOfPage":{"@id":"https:\/\/musicteam.com\/fr\/redevances-black-box\/#mainImage"},"datePublished":"2023-11-24T14:40:16-05:00","dateModified":"2025-12-09T13:28:17-05:00"},{"@type":"WebSite","@id":"https:\/\/musicteam.com\/fr\/#website","url":"https:\/\/musicteam.com\/fr\/","name":"MusicTeam\u00ae","description":"All-in-one platform for music makers","inLanguage":"fr-CA","publisher":{"@id":"https:\/\/musicteam.com\/fr\/#organization"}}]},"og:locale":"fr_CA","og:site_name":"MusicTeam\u00ae \u2013 All-in-one platform for music makers","og:type":"article","og:title":"La black box : ces redevances musicales perdues | MusicTeam\u00ae","og:description":"La bo\u00eete noire est un v\u00e9ritable fl\u00e9au de l'industrie musicale. O\u00f9 finissent ces millions de dollars qui devraient revenir aux artistes et quelle est la solution?","og:url":"https:\/\/musicteam.com\/fr\/redevances-black-box\/","og:image":"https:\/\/musicteam.com\/wp-content\/uploads\/2023\/11\/black-box-royalties.jpg","og:image:secure_url":"https:\/\/musicteam.com\/wp-content\/uploads\/2023\/11\/black-box-royalties.jpg","og:image:width":1100,"og:image:height":733,"article:published_time":"2023-11-24T19:40:16+00:00","article:modified_time":"2025-12-09T18:28:17+00:00","article:publisher":"https:\/\/www.facebook.com\/musicteamapp","twitter:card":"summary_large_image","twitter:title":"La black box : ces redevances musicales perdues | MusicTeam\u00ae","twitter:description":"La bo\u00eete noire est un v\u00e9ritable fl\u00e9au de l'industrie musicale. O\u00f9 finissent ces millions de dollars qui devraient revenir aux artistes et quelle est la solution?","twitter:image":"https:\/\/musicteam.com\/wp-content\/uploads\/2023\/11\/black-box-royalties.jpg"},"aioseo_meta_data":{"post_id":"2939","title":"La black box : ces redevances musicales perdues | MusicTeam\u00ae","description":"La bo\u00eete noire est un v\u00e9ritable fl\u00e9au de l'industrie musicale. O\u00f9 finissent ces millions de dollars qui devraient revenir aux artistes et quelle est la solution?","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":"2026-06-21 19:20:24","breadcrumb_settings":null,"limit_modified_date":false,"reviewed_by":"0","open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2023-11-24 19:37:37","updated":"2026-06-21 19:20:24"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/musicteam.com\/fr\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/musicteam.com\/fr\/categorie\/droits-musicaux\/\" title=\"Droits musicaux\">Droits musicaux<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\tLa black box: ces redevances perdues qui vous appartiennent\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/musicteam.com\/fr\/"},{"label":"Droits musicaux","link":"https:\/\/musicteam.com\/fr\/categorie\/droits-musicaux\/"},{"label":"La black box: ces redevances perdues qui vous appartiennent","link":"https:\/\/musicteam.com\/fr\/redevances-black-box\/"}],"_links":{"self":[{"href":"https:\/\/musicteam.com\/fr\/wp-json\/wp\/v2\/posts\/2939"}],"collection":[{"href":"https:\/\/musicteam.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/musicteam.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/musicteam.com\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/musicteam.com\/fr\/wp-json\/wp\/v2\/comments?post=2939"}],"version-history":[{"count":9,"href":"https:\/\/musicteam.com\/fr\/wp-json\/wp\/v2\/posts\/2939\/revisions"}],"predecessor-version":[{"id":5808,"href":"https:\/\/musicteam.com\/fr\/wp-json\/wp\/v2\/posts\/2939\/revisions\/5808"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/musicteam.com\/fr\/wp-json\/wp\/v2\/media\/2931"}],"wp:attachment":[{"href":"https:\/\/musicteam.com\/fr\/wp-json\/wp\/v2\/media?parent=2939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/musicteam.com\/fr\/wp-json\/wp\/v2\/categories?post=2939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/musicteam.com\/fr\/wp-json\/wp\/v2\/tags?post=2939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}